{"id":36676,"date":"2024-02-01T16:47:45","date_gmt":"2024-02-01T14:47:45","guid":{"rendered":"https:\/\/www.kithera.gr\/il-ponte-di-citera-costruito-per-un-amore\/"},"modified":"2025-03-08T15:00:24","modified_gmt":"2025-03-08T13:00:24","slug":"il-ponte-di-citera-costruito-per-un-amore","status":"publish","type":"post","link":"https:\/\/www.kithera.gr\/it\/il-ponte-di-citera-costruito-per-un-amore\/","title":{"rendered":"Il ponte di Citera costruito per un amore"},"content":{"rendered":"\n<div class=\"post-container\"><br\/>  <div class=\"infobox\"><br\/><br\/><p class=\"page-quote\"> <i>La Grecia \u00e8 un paese che ha letteralmente la pi\u00f9 ampia gamma di storia. Dalla preistoria ai giorni nostri, periodi ed eventi lasciano le loro impronte con monumenti storici che ci ricordano i periodi storici del nostro Paese.<\/i><\/p><br\/><br\/>Dagli insediamenti preistorici, all&#8217;epoca arcaica, al periodo classico, proseguendo fino all&#8217;epoca bizantina, arrivando fino ai nostri giorni, sono stati scoperti fino ai giorni nostri importanti tesori archeologici. <br\/><br\/>Molti di questi monumenti che si sono conservati fino ad oggi furono costruiti per vari motivi, per ragioni geostrategiche, per ragioni di difesa, per ragioni politiche, per ragioni economiche, ma il grande ponte di pietra a Katuni, nella Prateria Inferiore di Citera, fu costruito per un altro scopo. motivo, per amore di due giovani. <br\/><br\/>Secondo la leggenda locale, il <a href=\"https:\/\/www.kithera.gr\/it\/citera\/ponte-katuni\/\">ponte di Katuni<\/a>, considerato uno dei pi\u00f9 grandi ponti di pietra della Grecia , fu costruito nel 1826 dal commissario inglese McPhail, perch\u00e9 si era innamorato di una giovane ragazza che viveva nell&#8217;insediamento di fronte a Katuni. Quindi questo fu il motivo per costruire il ponte in modo che fosse un percorso pi\u00f9 breve per farle visita l\u00ec. <br\/><br\/>In effetti, questo ambizioso progetto faceva parte della pianificazione effettuata dagli inglesi, inclusa la costruzione e la segnaletica di nuove strade, nonch\u00e9 di scuole mantenute fino ad oggi, acquedotti, un porto e fari. Lo specifico ponte Katouni faceva parte dell&#8217;asse stradale che collegava la capitale Chora con il porto di Avlemonas, ed \u00e8 considerato la pi\u00f9 grande conquista tecnologica degli inglesi in <a href=\"https:\/\/www.kithera.gr\/it\/isola-citera\/\">Citera<\/a>.<br\/><br\/>Considerato uno dei ponti in pietra pi\u00f9 grandi della Grecia, \u00e8 lungo 110 m, largo 6 m e alto 15. Il gerphyri di Katouni poggia su 13 archi in perfetta simmetria tra loro, contiene 12 finestre cilindriche, ed \u00e8 stato realizzato sulla base sui piani del commissario inglese, l&#8217;ingegner Macphail.<br\/><br\/><\/div><br\/><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Grecia \u00e8 un paese che ha letteralmente la pi\u00f9 ampia gamma di storia. Dalla preistoria ai giorni nostri, periodi ed eventi lasciano le loro impronte con monumenti storici che ci ricordano i periodi storici del nostro Paese. Dagli insediamenti preistorici, all&#8217;epoca arcaica, al periodo classico, proseguendo fino all&#8217;epoca bizantina, arrivando fino ai nostri giorni, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25927,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[289],"tags":[],"class_list":["post-36676","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-citera"],"_links":{"self":[{"href":"https:\/\/www.kithera.gr\/it\/wp-json\/wp\/v2\/posts\/36676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kithera.gr\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kithera.gr\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kithera.gr\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kithera.gr\/it\/wp-json\/wp\/v2\/comments?post=36676"}],"version-history":[{"count":0,"href":"https:\/\/www.kithera.gr\/it\/wp-json\/wp\/v2\/posts\/36676\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kithera.gr\/it\/wp-json\/wp\/v2\/media\/25927"}],"wp:attachment":[{"href":"https:\/\/www.kithera.gr\/it\/wp-json\/wp\/v2\/media?parent=36676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kithera.gr\/it\/wp-json\/wp\/v2\/categories?post=36676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kithera.gr\/it\/wp-json\/wp\/v2\/tags?post=36676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}